{"id":57817,"date":"2025-10-21T09:00:00","date_gmt":"2025-10-21T07:00:00","guid":{"rendered":"https:\/\/www.ruschmineralen.nl\/product\/20492-dendriet-opaal-zilveren-hanger\/"},"modified":"2025-10-21T09:58:56","modified_gmt":"2025-10-21T07:58:56","slug":"20492-dendriten-opal-silber-anhanger","status":"publish","type":"product","link":"https:\/\/www.ruschmineralen.nl\/de\/product\/20492-dendriet-opaal-zilveren-hanger\/","title":{"rendered":"Dendrit Opal Silber Anh\u00e4nger"},"content":{"rendered":"<h2>Dendrit Opal Silber Anh\u00e4nger aus Indien<\/h2>\n<p><h3>Opal<\/h3>\n<p><a href=\"https:\/\/www.ruschmineralen.nl\/de\/typ\/opal\/\" target=\"_blank\">Opal<\/a> ist eine amorphe Form von Kiesels\u00e4ure mit variablem Wassergehalt. Bei Opalen unterscheidet man zwischen Edelopal, der f\u00fcr sein Farbspiel (Opaleszenz) bekannt ist, und gew\u00f6hnlichem Opal, der diesen Effekt nicht zeigt. Gew\u00f6hnlicher Opal kommt in verschiedenen Farben wie wei\u00df, rosa, blau, gr\u00fcn oder braun vor, meist mit einem wachsartigen bis glasartigen Glanz.<\/p>\n<p>Gro\u00dfe Vorkommen gibt es in Australien, Peru, Mexiko, Brasilien und den Vereinigten Staaten. Seine chemische Formel lautet SiO\u2082-nH\u2082O. Gew\u00f6hnlicher Opal bildet sich h\u00e4ufig in vulkanischen oder sediment\u00e4ren Umgebungen. Seine H\u00e4rte liegt zwischen 5,5 und 6,5 auf der Mohs-Skala.<\/p>\n<p>Zu den bekannten Sorten geh\u00f6ren der rosa peruanische Opal, der gr\u00fcne Opal, der schwarze Opal und der dendritische Opal, die sich durch ihre einzigartige Farbe und Einschl\u00fcsse auszeichnen.<\/p>\n<p><small><strong>Quellen: <\/strong><br \/><a href=\"https:\/\/www.mindat.org\/min-5981.html\" target=\"_blank\" rel=\"noopener\">Mindat.org<\/a>, <a href=\"https:\/\/www.gemdat.org\/gem-5981.html\" target=\"_blank\" rel=\"noopener\">Gemdat.org<\/a>, <a href=\"https:\/\/en.wikipedia.org\/wiki\/Opal\" target=\"_blank\" rel=\"noopener\">Wikipedia - Opal<\/a><\/small><\/p>\n<h3>Silber-Anh\u00e4nger<\/h3>\n<p>Die Silberanh\u00e4nger aus unserem Sortiment sind hochwertige Schmuckst\u00fccke mit sorgf\u00e4ltig ausgew\u00e4hlten (Edel-)Steinen, die in 925er Sterlingsilber gefasst sind. Diese Anh\u00e4nger sind nicht vergoldet, sondern komplett aus massivem Silber gefertigt. Die verwendeten Steine sind von deutlich h\u00f6herer Qualit\u00e4t, als dies bei dieser Art von Schmuck \u00fcblich ist.<\/p>\n<p>Die Anh\u00e4nger sind in verschiedenen Formen erh\u00e4ltlich, wobei der Schwerpunkt auf tr\u00e4nenf\u00f6rmigen und ovalen Designs liegt, die durch runde, quadratische und organische Varianten erg\u00e4nzt werden. Wir bieten mehr als 20 Steinarten an, darunter Amethyst, Chalcedon, Fluorit, Labradorit, Malachit, Tigerauge, Rutilquarz und Regenbogenmondstein. Die Gr\u00f6\u00dfen reichen von 2 bis 4 cm und wiegen jeweils etwa 4 bis 16 Gramm.<\/p>\n<\/p>","protected":false},"excerpt":{"rendered":"<p>Dendrit Opal Silber Anh\u00e4nger aus Indien<\/p>","protected":false},"featured_media":57750,"template":"","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"soort":[],"product_brand":[],"product_cat":[1348,1058],"product_tag":[1137],"class_list":["post-57817","product","type-product","status-publish","has-post-thumbnail","product_cat-unieke-producten","product_cat-zilveren-hangers","product_tag-uniek","pa_herkomst-india","pa_soort-dendriet-opaal","pa_soort-opaal","pa_verkoopeenheid-uniek","pa_vorm-zilveren-hanger","desktop-align-center","tablet-align-center","mobile-align-center","ast-product-gallery-layout-horizontal-slider","ast-product-gallery-with-no-image","ast-product-tabs-layout-horizontal","first","instock","sold-individually","taxable","shipping-taxable","product-type-simple"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.ruschmineralen.nl\/de\/wp-json\/wp\/v2\/product\/57817","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ruschmineralen.nl\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.ruschmineralen.nl\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ruschmineralen.nl\/de\/wp-json\/wp\/v2\/media\/57750"}],"wp:attachment":[{"href":"https:\/\/www.ruschmineralen.nl\/de\/wp-json\/wp\/v2\/media?parent=57817"}],"wp:term":[{"taxonomy":"soort","embeddable":true,"href":"https:\/\/www.ruschmineralen.nl\/de\/wp-json\/wp\/v2\/soort?post=57817"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.ruschmineralen.nl\/de\/wp-json\/wp\/v2\/product_brand?post=57817"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.ruschmineralen.nl\/de\/wp-json\/wp\/v2\/product_cat?post=57817"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.ruschmineralen.nl\/de\/wp-json\/wp\/v2\/product_tag?post=57817"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}